{"id":42,"date":"2011-08-01T15:06:16","date_gmt":"2011-08-01T13:06:16","guid":{"rendered":"http:\/\/www.fuss-cuckold.com\/cuckold\/?p=42"},"modified":"2011-05-06T15:12:21","modified_gmt":"2011-05-06T13:12:21","slug":"schenbecher-tramplingopfer-und-cuckold-sklave","status":"publish","type":"post","link":"http:\/\/www.fuss-cuckold.com\/cuckold\/2011\/08\/schenbecher-tramplingopfer-und-cuckold-sklave\/","title":{"rendered":"Aschenbecher, Tramplingopfer und Cuckold Sklave"},"content":{"rendered":"<p>Miss Cash erniedrigt ihren Sklaven heute einmal so richtig. Er muss ihr dabei zusehen, wie sie mit ihrem Freund rummacht. Dann soll der Arme auch noch ihr Fuss cuckold Sklave sein und ihre F\u00fc\u00dfe k\u00fcssen. Die Lady hat noch immer nicht genug ihn zu qu\u00e4len, so wird er auch noch mitten in die Eier getreten und er wird von ihr zum Dank noch als lebendiger Aschenbecher benutzt. Da haben die beiden Liebenden richtig was zu lachen.<\/p>\n<p><a href=\"http:\/\/www.yoogirls.com\/affin.php?cid=fuss-cuckold&amp;sid=564&amp;iid=18613\" target=\"_blank\"><img src=\"http:\/\/www.yoogirls.com\/storefiles\/564\/clip_images\/misscrash_cuckoldTV.gif\"><\/a><\/p>\n<p><a href=\"http:\/\/www.yoogirls.com\/affin.php?cid=fuss-cuckold&amp;sid=564&amp;iid=18613\">Hier kommst du zum Download Clip<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miss Cash erniedrigt ihren Sklaven heute einmal so richtig. Er muss ihr dabei zusehen, wie sie mit ihrem Freund rummacht. Dann soll der Arme auch noch ihr Fuss cuckold Sklave sein und ihre F\u00fc\u00dfe k\u00fcssen. Die Lady hat noch immer nicht genug ihn zu qu\u00e4len, so wird er auch noch mitten in die Eier getreten [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[32,3,11,33],"_links":{"self":[{"href":"http:\/\/www.fuss-cuckold.com\/cuckold\/wp-json\/wp\/v2\/posts\/42"}],"collection":[{"href":"http:\/\/www.fuss-cuckold.com\/cuckold\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.fuss-cuckold.com\/cuckold\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.fuss-cuckold.com\/cuckold\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.fuss-cuckold.com\/cuckold\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":0,"href":"http:\/\/www.fuss-cuckold.com\/cuckold\/wp-json\/wp\/v2\/posts\/42\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.fuss-cuckold.com\/cuckold\/wp-json\/wp\/v2\/media?parent=42"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.fuss-cuckold.com\/cuckold\/wp-json\/wp\/v2\/categories?post=42"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.fuss-cuckold.com\/cuckold\/wp-json\/wp\/v2\/tags?post=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}